{"id":657,"date":"2019-01-28T15:27:11","date_gmt":"2019-01-28T15:27:11","guid":{"rendered":"https:\/\/fetajorentacar.com\/?p=657"},"modified":"2019-06-06T17:02:24","modified_gmt":"2019-06-06T17:02:24","slug":"iglesia-de-santiago","status":"publish","type":"post","link":"https:\/\/fetajorentacar.com\/es\/iglesia-de-santiago\/","title":{"rendered":"Igl\u00e9sia de Santiago"},"content":{"rendered":"<h2>Iglesia de Santiago<\/h2>\n<p><span style=\"font-weight: 400;\">Situaci\u00f3n: <\/span><a href=\"https:\/\/goo.gl\/maps\/y29LK9d9BFB2\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">https:\/\/goo.gl\/maps\/y29LK9d9BFB2<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Visitamos la ciudad de M\u00e1laga entrando en ella de la misma forma que lo hicieron los reyes cat\u00f3lico en el a\u00f1o 1487, por la llamada calle Real d\u00f3nde se ubicaba la puerta de acceso a la calle llamada la Puerta de Granada que forma parte de la muralla que rodeaba la antigua ciudad. \u00a0La mejor forma de descubrir M\u00e1laga es con <\/span><a href=\"https:\/\/fetajorentacar.com\/es\/\"><span style=\"font-weight: 400;\">rent a car aeropuerto de Malaga\u00a0<\/span><\/a><\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/fetajorentacar.com\/wp-content\/uploads\/2019\/01\/Iglesia-de-santiago-Malaga.jpg\" alt=\"Igl\u00e9sia de Santiago de Rent a car M\u00e1laga\" width=\"100%\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Al acceder a la calle nos queda a mano derecha el antiguo barrio de la morer\u00eda y a mano izquierda la iglesia de Santiago, una de las 4 primeras iglesias que construyeron los reyes cat\u00f3licos despu\u00e9s de la reconquista.<\/span><\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/fetajorentacar.com\/wp-content\/uploads\/2016\/11\/Torre-iglesia-santiago-Malga.jpg\" alt=\"Torre de la igl\u00e9sia de Santiago\" width=\"100%\" \/><\/p>\n<p><span style=\"font-weight: 400;\">La torre de la iglesia es de estilo G\u00f3tico mud\u00e9jar, la torre est\u00e1 decorada con motivos que recuerdan a las torres del norte de marruecos, T\u00e1nger. La iglesia de Santiago mezcla dos estilos arquitect\u00f3nicos, el g\u00f3tico, la corriente arquitect\u00f3nica vinculada a la construcci\u00f3n de iglesias por excelencia y el mud\u00e9jar, un estilo arquitect\u00f3nico \u00fanico en la pen\u00ednsula ib\u00e9rica. \u00a0Visita M\u00e1laga con Fetajo <\/span><a href=\"https:\/\/fetajorentacar.com\/\"><span style=\"font-weight: 400;\">Car Hire Malaga airport<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/fetajorentacar.com\/wp-content\/uploads\/2019\/01\/parroquia-santiago-malaga.jpg\" alt=\"Puerta parroquia Santiago Car Hire M\u00e1laga\" width=\"100%\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Una curiosidad de la parroquia de Santiago es que la puerta de entrada actualmente cerrada era la antigua iglesia construida al inicio del siglo XVI y fue la primera iglesia construida de M\u00e1laga.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esta iglesia fu\u00e9 bautizado uno de los Malague\u00f1os m\u00e1s internacionales de la historia, en la fachada de la iglesia hay una placa conmemorativa donde se identifica como el 10 de noviembre de 1881 se Bautiz\u00f3 a Pablo Picasso en esta parroquia. \u00c9l naci\u00f3 en una plaza muy cerca de la iglesia, en la plaza de la Merced. Podr\u00e1s visitar la iglesia de Santiago con Fetajo <\/span><a href=\"https:\/\/fetajorentacar.com\/\"><span style=\"font-weight: 400;\">car Hire Mijas<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/fetajorentacar.com\/wp-content\/uploads\/2019\/01\/interior-iglesia-santiago-malaga.jpg\" alt=\"Interior Barroco igl\u00e9sia Santiago Car Hire Malaga Airport\" width=\"100%\" \/><\/p>\n<p><span style=\"font-weight: 400;\">En el interior de la iglesia se puede admirar una de las joyas del arte sacro de la ciudad de M\u00e1laga. En la nave central se puede apreciar una iglesia de estilo basilical, pero el interior la parroquia no tiene rasgos como en el exterior del edificio con los estilos g\u00f3ticos mud\u00e9jar, el interior tiene una decoraci\u00f3n barroca caracter\u00edstica de la M\u00e1laga cristiana del siglo XVIII.<\/span><\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/fetajorentacar.com\/wp-content\/uploads\/2019\/01\/iglesia-jesus-el-rico-Malaga.jpg\" alt=\"Jesus el Rico M\u00e1laga Rent a car M\u00e1laga\" width=\"100%\" \/><\/p>\n<p><span style=\"font-weight: 400;\">La veneraci\u00f3n y la importancia de la imagen de Jes\u00fas el Rico recae por la historia que guarda, en el siglo XVIII cuando la peste y el c\u00f3lera asolan la ciudad de M\u00e1laga, tantos enfermos y muertos llevaron a prohibir las procesiones de la semana santa por este motivo. \u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los prisioneros de la c\u00e1rcel de M\u00e1laga pidieron al director realizar la procesi\u00f3n, \u00e9ste obedeciendo la prohibici\u00f3n se neg\u00f3 y los prisioneros lograron escaparse. Dicen las leyendas que todos los prisioneros despu\u00e9s de mostrar la imagen por las calles de M\u00e1laga regresaron a la c\u00e1rcel menos uno, \u00e9ste se qued\u00f3 cuidando a un amigo en c\u00f3lera y regres\u00f3 a la ma\u00f1ana siguiente. Tres d\u00edas despu\u00e9s de los hechos M\u00e1laga se recupera de la peste. Descubre M\u00e1laga con <\/span><a href=\"https:\/\/fetajorentacar.com\/\"><span style=\"font-weight: 400;\">Rent a car M\u00e1laga Airport<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Esta historia llega a o\u00eddos del rey Carlos III (el rey alcalde de Madrid), al o\u00edr la historia decidi\u00f3 que a partir de aquel momento en M\u00e1laga se permitir\u00eda liberar a un preso cada a\u00f1o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para m\u00e1s informaci\u00f3n de <\/span><a href=\"https:\/\/fetajorentacar.com\/es\/noticias\/\"><span style=\"font-weight: 400;\">Turismo en M\u00e1laga <\/span><\/a><span style=\"font-weight: 400;\">visiten nuestro Blog, para alquiler un Coche en M\u00e1laga visiten nuestra web<\/span><a href=\"https:\/\/fetajorentacar.com\/\"><span style=\"font-weight: 400;\"> www.fetajorentacar.com<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iglesia de Santiago Situaci\u00f3n: https:\/\/goo.gl\/maps\/y29LK9d9BFB2 Visitamos la ciudad de M\u00e1laga entrando en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"Iglesia de Santiago M\u00e1laga | Fetajo Rent a Car","rank_math_description":"Descubre iglesia de santiago m\u00e1laga en M\u00e1laga con Fetajo Rent a Car. Alquila tu coche en el aeropuerto de M\u00e1laga y explora la Costa del Sol.","rank_math_canonical_url":"","rank_math_focus_keyword":"iglesia de santiago m\u00e1laga"},"categories":[10],"tags":[],"class_list":["post-657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-en-malaga"],"_links":{"self":[{"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/posts\/657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/comments?post=657"}],"version-history":[{"count":0,"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/posts\/657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/media\/662"}],"wp:attachment":[{"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/media?parent=657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/categories?post=657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fetajorentacar.com\/es\/wp-json\/wp\/v2\/tags?post=657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}